{"id":28804,"date":"2023-01-08T14:00:54","date_gmt":"2023-01-08T13:00:54","guid":{"rendered":"https:\/\/store.csslabs.de\/wp20\/product\/ga-ipad-pro-12-9-5-gen-defender-case\/"},"modified":"2026-07-14T20:33:22","modified_gmt":"2026-07-14T20:33:22","slug":"ga-ipad-pro-12-9-5-gen-defender-case","status":"publish","type":"product","link":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/","title":{"rendered":"GA iPad Pro 12,9&#8243; (5. Gen.) Defender Case"},"content":{"rendered":"<p>&#8222;Ger&auml;teadapter zur Montage von iPad Pro 12,9&#8243;&#8220; (3., 4. oder 5. Gen &#8211; 2018, 2020 oder 2021) in OtterBox Defender Schutzh&uuml;lle an Rehadapts universeller Ger&auml;teaufnahme (UGA). UGA und OtterBox nicht enthalten. &#8222;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"featured_media":28805,"template":"","meta":[],"product_cat":[380,372],"product_tag":[],"class_list":["post-28804","product","type-product","status-publish","has-post-thumbnail","product_cat-380","product_cat-372","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GA iPad Pro 12,9&quot; (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GA iPad Pro 12,9&quot; (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/\" \/>\n<meta property=\"og:site_name\" content=\"CSS B2B Store \u2013 CSS MicroSystems GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/css.microsystems\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T20:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/Artikelbilder\/RD-16.12280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/\",\"url\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/\",\"name\":\"GA iPad Pro 12,9\\\" (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/wp-content\\\/uploads\\\/Artikelbilder\\\/RD-16.12280.jpg\",\"datePublished\":\"2023-01-08T13:00:54+00:00\",\"dateModified\":\"2026-07-14T20:33:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/#primaryimage\",\"url\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/wp-content\\\/uploads\\\/Artikelbilder\\\/RD-16.12280.jpg\",\"contentUrl\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/wp-content\\\/uploads\\\/Artikelbilder\\\/RD-16.12280.jpg\",\"width\":500,\"height\":375,\"caption\":\"GA iPad Pro 12,9\\\" (5. Gen.) Defender Case\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/produkt\\\/ga-ipad-pro-12-9-5-gen-defender-case\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GA iPad Pro 12,9&#8243; (5. Gen.) Defender Case\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#website\",\"url\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/\",\"name\":\"CSS B2B Store \u2013 CSS MicroSystems GmbH\",\"description\":\"The Assistive Technology Factory | B2B Store from The Assistiv Technology Factory\",\"publisher\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#organization\",\"name\":\"CSS B2B Store \u2013 CSS MicroSystems GmbH\",\"url\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/CSS-Icon-ohneEffekte_web.png\",\"contentUrl\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/CSS-Icon-ohneEffekte_web.png\",\"width\":1243,\"height\":1278,\"caption\":\"CSS B2B Store \u2013 CSS MicroSystems GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/store.csslabs.de\\\/wp20\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/css.microsystems\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GA iPad Pro 12,9\" (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/","og_locale":"de_DE","og_type":"article","og_title":"GA iPad Pro 12,9\" (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH","og_description":"&nbsp;","og_url":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/","og_site_name":"CSS B2B Store \u2013 CSS MicroSystems GmbH","article_publisher":"https:\/\/www.facebook.com\/css.microsystems","article_modified_time":"2026-07-14T20:33:22+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/Artikelbilder\/RD-16.12280.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/","url":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/","name":"GA iPad Pro 12,9\" (5. Gen.) Defender Case - CSS B2B Store \u2013 CSS MicroSystems GmbH","isPartOf":{"@id":"https:\/\/store.csslabs.de\/wp20\/#website"},"primaryImageOfPage":{"@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/#primaryimage"},"image":{"@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/#primaryimage"},"thumbnailUrl":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/Artikelbilder\/RD-16.12280.jpg","datePublished":"2023-01-08T13:00:54+00:00","dateModified":"2026-07-14T20:33:22+00:00","breadcrumb":{"@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/#primaryimage","url":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/Artikelbilder\/RD-16.12280.jpg","contentUrl":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/Artikelbilder\/RD-16.12280.jpg","width":500,"height":375,"caption":"GA iPad Pro 12,9\" (5. Gen.) Defender Case"},{"@type":"BreadcrumbList","@id":"https:\/\/store.csslabs.de\/wp20\/produkt\/ga-ipad-pro-12-9-5-gen-defender-case\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/store.csslabs.de\/wp20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/store.csslabs.de\/wp20\/shop\/"},{"@type":"ListItem","position":3,"name":"GA iPad Pro 12,9&#8243; (5. Gen.) Defender Case"}]},{"@type":"WebSite","@id":"https:\/\/store.csslabs.de\/wp20\/#website","url":"https:\/\/store.csslabs.de\/wp20\/","name":"CSS B2B Store \u2013 CSS MicroSystems GmbH","description":"The Assistive Technology Factory | B2B Store from The Assistiv Technology Factory","publisher":{"@id":"https:\/\/store.csslabs.de\/wp20\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/store.csslabs.de\/wp20\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/store.csslabs.de\/wp20\/#organization","name":"CSS B2B Store \u2013 CSS MicroSystems GmbH","url":"https:\/\/store.csslabs.de\/wp20\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/store.csslabs.de\/wp20\/#\/schema\/logo\/image\/","url":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/2022\/05\/CSS-Icon-ohneEffekte_web.png","contentUrl":"https:\/\/store.csslabs.de\/wp20\/wp-content\/uploads\/2022\/05\/CSS-Icon-ohneEffekte_web.png","width":1243,"height":1278,"caption":"CSS B2B Store \u2013 CSS MicroSystems GmbH"},"image":{"@id":"https:\/\/store.csslabs.de\/wp20\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/css.microsystems"]}]}},"_links":{"self":[{"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/product\/28804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/product\/28804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/media\/28805"}],"wp:attachment":[{"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/media?parent=28804"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/product_cat?post=28804"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/store.csslabs.de\/wp20\/wp-json\/wp\/v2\/product_tag?post=28804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}